{"id":10356,"date":"2021-07-21T20:38:59","date_gmt":"2021-07-21T20:38:59","guid":{"rendered":"https:\/\/fcpr.org\/?p=10356"},"modified":"2023-03-21T11:53:16","modified_gmt":"2023-03-21T15:53:16","slug":"celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios","status":"publish","type":"post","link":"https:\/\/www.fcpr.org\/en\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/","title":{"rendered":"First regional meeting held in the southwest to create national organization of community aqueducts"},"content":{"rendered":"<p><strong>San Juan | Mi\u00e9rcoles, 21 de julio de 2021 | <\/strong>L\u00edderes de m\u00e1s de sesenta acueductos comunitarios ubicados en el \u00e1rea suroeste de la isla se reunir\u00e1n el pr\u00f3ximo s\u00e1bado, 24 de julio de 2021 en el Centro de Convenciones de la Monta\u00f1a, en Corcovada, A\u00f1asco, para celebrar el <strong>1er Junte de Acueductos Comunitarios de Puerto Rico<\/strong>, facilitado por la <strong>Puerto Rico Community Foundation<\/strong> (FCPR). El encuentro es el primero de cuatro que se celebrar\u00e1n durante el a\u00f1o con el fin de que representantes de cada regi\u00f3n creen lo que ser\u00e1 una organizaci\u00f3n nacional que agrupe, apoye y represente a los aproximadamente 242 acueductos comunitarios que existen en la isla.<\/p>\n\n\n\n<p>The initiative is part of the <em>Water for Us Program<\/em> de la FCPR y es la secuela de tres encuentros regionales realizados durante el 2019 en A\u00f1asco, Aguas Buenas y Adjuntas. En los encuentros previos, l\u00edderes de estas comunidades compartieron retos y saberes e identificaron la necesidad de formalizar un grupo nacional que les represente para atender sus retos y oportunidades. La iniciativa facilitada por la FCPR cuenta con una aportaci\u00f3n de $250,000 de <strong>Global Giving.<\/strong><\/p>\n\n\n\n<p>Se espera que de este primer encuentro regional surjan delegados de la regi\u00f3n, situaci\u00f3n que debe repetirse en los pr\u00f3ximos tres encuentros. De esta forma, un quinto encuentro se celebrar\u00eda antes de que finalice el a\u00f1o para elegir lo que ser\u00eda la junta general de una organizaci\u00f3n de acueductos comunitarios de Puerto Rico.<\/p>\n\n\n\n<p>\u201cLograr el acceso a agua potable en comunidades remotas de Puerto Rico es complicado, y los l\u00edderes de los acueductos llevamos tiempo tratando de facilitar los procesos. Con esta iniciativa, al fin vemos una oportunidad para agruparnos bajo una sola organizaci\u00f3n gracias al apoyo de la Fundaci\u00f3n Comunitaria de Puerto Rico y otras entidades\u201d, dijo <strong>Iris Gonz\u00e1lez, <\/strong>presidenta del Comit\u00e9 Comunal de Corcovada, comunidad anfitriona del encuentro.<\/p>\n\n\n\n<p>En Puerto Rico hay cerca de 242 acueductos comunitarios, ubicados en 43 municipios, en su mayor\u00eda en \u00e1reas rurales remotas y monta\u00f1osas. Estos suplen agua potable al 3% de la poblaci\u00f3n, lo que representa unas 120,000 personas aproximadamente.&nbsp;A diario estas comunidades enfrentan retos relacionados con la falta de energ\u00eda para operar el bombeo, contaminaci\u00f3n de cuerpos de agua que los nutre y falta de presupuesto para mantenerles funcionando en \u00f3ptimas condiciones, y as\u00ed poder suplir la demanda de su comunidad, entre otros.<\/p>\n\n\n\n<p>\u201cEl desarrollo de esta iniciativa est\u00e1 cimentada sobre los principios de participaci\u00f3n, representatividad y sustentabilidad. Los juntes que se han llevado a cabo y lo que se planifica a nivel nacional, no es otra cosa que la activaci\u00f3n organizada del capital social de estas comunidades para alcanzar el bien com\u00fan y el acceso a agua potable para todo residente de estas comunidades. Es la autogesti\u00f3n desde la misma base de la comunidad. Nuestro rol es facilitar el proceso para que pueda ser sostenible a largo plazo. Es un gran paso, y nos honra ser parte del mismo,\u201d dijo el presidente y principal oficial ejecutivo, el <strong>doctor Nelson I. Col\u00f3n Tarrats.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Los l\u00edderes que asistan al encuentro regional deben de representar acueductos comunitarios en los pueblos de Adjuntas, Aguada, Aguadilla, A\u00f1asco, Guayanilla, Lares, Las Mar\u00edas, Pe\u00f1uelas, Ponce, San Germ\u00e1n, San Sebasti\u00e1n y Yauco. La agenda de trabajo inicia a las 9:00 a.m. y termina a las 3:00 p.m. \u2013 habr\u00e1 almuerzo y se ejecutar\u00e1 un protocolo para el COVID-19. Es necesario confirmar asistencia a Iris Gonz\u00e1lez al 787-519-3135 o Juan Cruz al 787-962-7700.&nbsp;<\/p>\n\n\n\n<p>La FCPR anunciar\u00e1 m\u00e1s adelante los lugares donde se celebrar\u00e1n los pr\u00f3ximos tres encuentros regionales en sus redes sociales: Facebook (@FundacionComunitaria), Instagram&nbsp; (@fundacioncomunitaria) y Twitter (@FComunitaria).&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>San Juan | Mi\u00e9rcoles, 21 de julio de 2021 | L\u00edderes de m\u00e1s de sesenta acueductos comunitarios ubicados en el \u00e1rea suroeste de la isla se reunir\u00e1n el pr\u00f3ximo s\u00e1bado, 24 de julio de 2021 en el Centro de Convenciones de la Monta\u00f1a, en Corcovada, A\u00f1asco, para celebrar el 1er Junte de Acueductos Comunitarios de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[32],"tags":[107,115,715],"class_list":["post-10356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","tag-acueductos-comunitarios","tag-agua-pa-nosotros","tag-comunicado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios - Fundaci\u00f3n Comunitaria de Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcpr.org\/en\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios\" \/>\n<meta property=\"og:description\" content=\"San Juan | Mi\u00e9rcoles, 21 de julio de 2021 | L\u00edderes de m\u00e1s de sesenta acueductos comunitarios ubicados en el \u00e1rea suroeste de la isla se reunir\u00e1n el pr\u00f3ximo s\u00e1bado, 24 de julio de 2021 en el Centro de Convenciones de la Monta\u00f1a, en Corcovada, A\u00f1asco, para celebrar el 1er Junte de Acueductos Comunitarios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcpr.org\/en\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Comunitaria de Puerto Rico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionComunitaria\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-21T20:38:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FCPR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:site\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"FCPR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/\"},\"author\":{\"name\":\"FCPR\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/8231c5ec4d08352e6a4ce3702e35f3c3\"},\"headline\":\"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios\",\"datePublished\":\"2021-07-21T20:38:59+00:00\",\"dateModified\":\"2023-03-21T15:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg\",\"keywords\":[\"Acueductos comunitarios\",\"agua pa nosotros\",\"Comunicado\"],\"articleSection\":[\"comunicados\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/\",\"name\":\"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios - Fundaci\u00f3n Comunitaria de Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg\",\"datePublished\":\"2021-07-21T20:38:59+00:00\",\"dateModified\":\"2023-03-21T15:53:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg\",\"width\":2160,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fcpr.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"description\":\"Fortaleciendo el Capital Comunitario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fcpr.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"width\":221,\"height\":32,\"caption\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionComunitaria\",\"https:\\\/\\\/x.com\\\/FComunitaria\",\"https:\\\/\\\/www.instagram.com\\\/fundacioncomunitaria\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGGW21eIGw6NRin0BrylmWg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/8231c5ec4d08352e6a4ce3702e35f3c3\",\"name\":\"FCPR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g\",\"caption\":\"FCPR\"},\"url\":\"https:\\\/\\\/www.fcpr.org\\\/en\\\/author\\\/perla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios - Fundaci\u00f3n Comunitaria de Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcpr.org\/en\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/","og_locale":"en_US","og_type":"article","og_title":"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios","og_description":"San Juan | Mi\u00e9rcoles, 21 de julio de 2021 | L\u00edderes de m\u00e1s de sesenta acueductos comunitarios ubicados en el \u00e1rea suroeste de la isla se reunir\u00e1n el pr\u00f3ximo s\u00e1bado, 24 de julio de 2021 en el Centro de Convenciones de la Monta\u00f1a, en Corcovada, A\u00f1asco, para celebrar el 1er Junte de Acueductos Comunitarios de [&hellip;]","og_url":"https:\/\/www.fcpr.org\/en\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/","og_site_name":"Fundaci\u00f3n Comunitaria de Puerto Rico","article_publisher":"https:\/\/www.facebook.com\/FundacionComunitaria","article_published_time":"2021-07-21T20:38:59+00:00","article_modified_time":"2023-03-21T15:53:16+00:00","og_image":[{"width":2160,"height":1440,"url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg","type":"image\/jpeg"}],"author":"FCPR","twitter_card":"summary_large_image","twitter_creator":"@FComunitaria","twitter_site":"@FComunitaria","twitter_misc":{"Written by":"FCPR","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#article","isPartOf":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/"},"author":{"name":"FCPR","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/8231c5ec4d08352e6a4ce3702e35f3c3"},"headline":"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios","datePublished":"2021-07-21T20:38:59+00:00","dateModified":"2023-03-21T15:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"image":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg","keywords":["Acueductos comunitarios","agua pa nosotros","Comunicado"],"articleSection":["comunicados"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/","url":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/","name":"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios - Fundaci\u00f3n Comunitaria de Puerto Rico","isPartOf":{"@id":"https:\/\/www.fcpr.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#primaryimage"},"image":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg","datePublished":"2021-07-21T20:38:59+00:00","dateModified":"2023-03-21T15:53:16+00:00","breadcrumb":{"@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#primaryimage","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/07\/Reunion-comunitaria-relacionada-con-los-acueductos-comunitarios-en-Corcovada-Anasco.-Archivo-min.jpg","width":2160,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcpr.org\/celebran-primer-encuentro-regional-en-el-suroeste-para-crear-organizacion-nacional-de-acueductos-comunitarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fcpr.org\/"},{"@type":"ListItem","position":2,"name":"Celebran primer encuentro regional en el suroeste para crear organizaci\u00f3n nacional de acueductos comunitarios"}]},{"@type":"WebSite","@id":"https:\/\/www.fcpr.org\/#website","url":"https:\/\/www.fcpr.org\/","name":"Puerto Rico Community Foundation","description":"Strengthening Community Capital","publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcpr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fcpr.org\/#organization","name":"Puerto Rico Community Foundation","url":"https:\/\/www.fcpr.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","width":221,"height":32,"caption":"Fundaci\u00f3n Comunitaria de Puerto Rico"},"image":{"@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionComunitaria","https:\/\/x.com\/FComunitaria","https:\/\/www.instagram.com\/fundacioncomunitaria\/","https:\/\/www.youtube.com\/channel\/UCGGW21eIGw6NRin0BrylmWg"]},{"@type":"Person","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/8231c5ec4d08352e6a4ce3702e35f3c3","name":"FCPR","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe4949f530883214bb05bea93cfcc96c4a6905a6c377112f07f806bafc3a2e5d?s=96&d=blank&r=g","caption":"FCPR"},"url":"https:\/\/www.fcpr.org\/en\/author\/perla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/10356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/comments?post=10356"}],"version-history":[{"count":1,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/10356\/revisions"}],"predecessor-version":[{"id":10357,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/10356\/revisions\/10357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media\/10358"}],"wp:attachment":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media?parent=10356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/categories?post=10356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/tags?post=10356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}