{"id":11582,"date":"2022-08-05T13:48:23","date_gmt":"2022-08-05T13:48:23","guid":{"rendered":"https:\/\/fcpr.org\/?p=11582"},"modified":"2023-03-21T11:40:05","modified_gmt":"2023-03-21T15:40:05","slug":"celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra","status":"publish","type":"post","link":"https:\/\/www.fcpr.org\/en\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/","title":{"rendered":"Dialogue on decolonizing Caribbean philanthropy to be held during annual international Black Philanthropy Month conference"},"content":{"rendered":"<p><strong>San Juan | Viernes, 5 de agosto de 2022<\/strong> | En el marco del <strong>Mes de la Filantrop\u00eda Negra<\/strong> (<a href=\"https:\/\/www.blackphilanthropymonth.com\/2018\/7\/30\/5erlelt74otobq4m17lxqi1l533bob\">BPM<\/a> por sus siglas en ingl\u00e9s), especialistas en el tema de la filantrop\u00eda afrodescendiente y caribe\u00f1a participar\u00e1n en uno de los paneles de la <strong><em>Cumbre Anual 2022, Urgencia feroz del ahora, del sue\u00f1o a la acci\u00f3n<\/em><\/strong>, que impulsa esta celebraci\u00f3n internacional organizada por <a href=\"https:\/\/thewisefund.org\/\"><strong>The Women Invested to Save Earth Fund<\/strong><\/a><strong>. <\/strong>El panel regional <strong><em>Financiamiento para la equidad: inversiones en descolonizaci\u00f3n<\/em><\/strong><em> <strong>y justicia reparadora en el Caribe<\/strong>, <\/em>se celebrar\u00e1 de forma virtual el mi\u00e9rcoles, 17 de agosto de 1:00 p.m. a 2:30 p.m. Para registrarse, visite este enlace: <a href=\"https:\/\/hopin.com\/events\/bpm-2022-the-caribbean\">BPM 2022 The Caribbean.<\/a><\/p>\n\n\n\n<p>Durante el panel, que es libre de costo y forma parte de seis eventos h\u00edbridos que se celebrar\u00e1n durante este mes, se profundizar\u00e1 en la descolonizaci\u00f3n de la filantrop\u00eda y se abordar\u00e1 el acercamiento &nbsp;imperialista y patriarcal que suele prevalecer. El grupo de panelistas estar\u00e1 integrado por: <strong>Susan Batten Taylor<\/strong>, president of <em>Association of Black Foundation Executives <\/em>(ABFE); <a><strong>Olga Chapman Rivera<\/strong>, fundadora y jefa de <em>Go-Getter en BRAAVE<\/em><\/a>; y <strong>Deanna James<\/strong>, president of <a href=\"https:\/\/www.stxfoundation.org\/?fbclid=IwAR3ZyPiWaHfmE38IFe3TIqe3zYlTpgtIK009nRrceuMai84iJ4IrOWaiydY\"><em>St. Croix Foundation.<\/em><\/a><em> <\/em>La oradora principal ser\u00e1 <strong>Dana Francois<\/strong> from <em>W.K. Kellogg Foundation<\/em>, quien ofrecer\u00e1 informaci\u00f3n sobre algunas de las conversaciones regionales m\u00e1s actualizadas, en torno a la descolonizaci\u00f3n y las reparaciones, as\u00ed como el papel de la filantrop\u00eda en torno al financiamiento de la justicia reparadora en toda la di\u00e1spora (Estados Unidos, el Caribe y \u00c1frica). El panel ser\u00e1 moderado por la doctora <strong>Marissel Hern\u00e1ndez Romero<\/strong>, directora del Instituto para la Construcci\u00f3n de Equidad Racial en las Am\u00e9ricas (ICERLA), una iniciativa de la <a href=\"https:\/\/www.fcpr.org\/en\/\">Puerto Rico Community Foundation<\/a> (FCPR).<\/p>\n\n\n\n<p>\u201cPor segunda ocasi\u00f3n, nos honra ser parte del BPM. Hemos colaborado estrechamente con <em>St. Croix Foundation, <\/em>la cual ha llevado el gran peso de dise\u00f1ar el panel de este a\u00f1o. El an\u00e1lisis ponderado sobre la manera en que se invierte filantr\u00f3picamente en temas de descolonizaci\u00f3n y justicia reparadora debe provocar reflexi\u00f3n y acci\u00f3n sobre las brechas que existen y que contin\u00faan promoviendo la inequidad en nuestras comunidades afrodescendientes\u201d, indic\u00f3 el Dr. Nelson I. Col\u00f3n Tarrats, presidente y principal oficial ejecutivo de la FCPR.<\/p>\n\n\n\n<p>La serie de conferencias que comenz\u00f3 el 3 de agosto, cuenta con la participaci\u00f3n de l\u00edderes de Canad\u00e1, \u00c1frica, Brasil, Estados Unidos y el Caribe. Tambi\u00e9n habr\u00e1 participaci\u00f3n de l\u00edderes de la di\u00e1spora negra. Las conferencias enfocar\u00e1n en presentar los retos, oportunidades y estrategias para promover acceso equitativo y justo a capital financiero para las personas afrodescendientes en todo el mundo. Tambi\u00e9n se busca fortalecer a la comunidad global y organizaciones que trabajan con las comunidades negras, que adem\u00e1s de ser impactadas en su diario vivir por el racismo imperante, se han vulnerabilizado a\u00fan m\u00e1s por la pandemia del COVID-19 y la recesi\u00f3n.<\/p>\n\n\n\n<p>Las conferencias est\u00e1n programadas para los d\u00edas 4, 9, 10, 17 y 31 de agosto. El registro en l\u00ednea para el resto de los eventos est\u00e1 disponible en&nbsp; <a href=\"https:\/\/hopin.com\/events\/bpm-2022-summit\"><strong>BPM 2022 US Global Summit Kick Off &#8211; Aug 03 | Hopin<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p>El Mes de la Filantrop\u00eda Negra, ahora en su und\u00e9cimo a\u00f1o, es un programa de <em>The Women Invested to Save Earth Fund,<\/em> que culmina en una cumbre multinacional cada agosto, en una celebraci\u00f3n global y una campa\u00f1a concertada para elevar la equidad en las donaciones y la financiaci\u00f3n de los afrodescendientes. Incubada en 2001 por su fundadora, la doctora <strong>Jackie Bouvier Copeland<\/strong>, con el apoyo de <strong>Reunity <\/strong>\u2013anteriormente la Red Panafricana de Filantrop\u00eda de Mujeres\u2013 BPM se lanz\u00f3 en 2011 con su primera cumbre mundial oficial para conmemorar el <a><em>Decenio Internacional de los Afrodescendientes<\/em><\/a> (2015-2024). El Mes de la Filantrop\u00eda Negra tiene 9 millones de personas involucradas en 60 pa\u00edses, lo que lo convierte en la \u00fanica coalici\u00f3n y movimiento de la comunidad de la di\u00e1spora global del mundo que celebra y empodera la financiaci\u00f3n negra en todas sus formas.<\/p>\n\n\n\n<p>El evento es libre de costo y se invita a la poblaci\u00f3n en general, particularmente l\u00edderes de organizaciones sin fines de lucro y fundaciones, legisladores, profesionales de la academia, estudiantes y financiadores locales o globales.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>San Juan | Viernes, 5 de agosto de 2022 | En el marco del Mes de la Filantrop\u00eda Negra (BPM por sus siglas en ingl\u00e9s), especialistas en el tema de la filantrop\u00eda afrodescendiente y caribe\u00f1a participar\u00e1n en uno de los paneles de la Cumbre Anual 2022, Urgencia feroz del ahora, del sue\u00f1o a la acci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":11584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[32],"tags":[715,447],"class_list":["post-11582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","tag-comunicado","tag-equidad-racial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra - Fundaci\u00f3n Comunitaria de Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcpr.org\/en\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra\" \/>\n<meta property=\"og:description\" content=\"San Juan | Viernes, 5 de agosto de 2022 | En el marco del Mes de la Filantrop\u00eda Negra (BPM por sus siglas en ingl\u00e9s), especialistas en el tema de la filantrop\u00eda afrodescendiente y caribe\u00f1a participar\u00e1n en uno de los paneles de la Cumbre Anual 2022, Urgencia feroz del ahora, del sue\u00f1o a la acci\u00f3n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcpr.org\/en\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Comunitaria de Puerto Rico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionComunitaria\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-05T13:48:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1055\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Libni Sanjurjo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:site\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Libni Sanjurjo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/\"},\"author\":{\"name\":\"Libni Sanjurjo\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/49ddf8247898f4a287fad4df52650612\"},\"headline\":\"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra\",\"datePublished\":\"2022-08-05T13:48:23+00:00\",\"dateModified\":\"2023-03-21T15:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/\"},\"wordCount\":744,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2022-BPM-Summit-Poster-min-e1659707280567.png\",\"keywords\":[\"Comunicado\",\"Equidad Racial\"],\"articleSection\":[\"comunicados\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/\",\"name\":\"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra - Fundaci\u00f3n Comunitaria de Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2022-BPM-Summit-Poster-min-e1659707280567.png\",\"datePublished\":\"2022-08-05T13:48:23+00:00\",\"dateModified\":\"2023-03-21T15:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2022-BPM-Summit-Poster-min-e1659707280567.png\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/2022-BPM-Summit-Poster-min-e1659707280567.png\",\"width\":1055,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fcpr.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"description\":\"Fortaleciendo el Capital Comunitario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fcpr.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"width\":221,\"height\":32,\"caption\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionComunitaria\",\"https:\\\/\\\/x.com\\\/FComunitaria\",\"https:\\\/\\\/www.instagram.com\\\/fundacioncomunitaria\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGGW21eIGw6NRin0BrylmWg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/49ddf8247898f4a287fad4df52650612\",\"name\":\"Libni Sanjurjo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"caption\":\"Libni Sanjurjo\"},\"sameAs\":[\"https:\\\/\\\/fcpr.org\"],\"url\":\"https:\\\/\\\/www.fcpr.org\\\/en\\\/author\\\/lisanfcpr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra - Fundaci\u00f3n Comunitaria de Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcpr.org\/en\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/","og_locale":"en_US","og_type":"article","og_title":"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra","og_description":"San Juan | Viernes, 5 de agosto de 2022 | En el marco del Mes de la Filantrop\u00eda Negra (BPM por sus siglas en ingl\u00e9s), especialistas en el tema de la filantrop\u00eda afrodescendiente y caribe\u00f1a participar\u00e1n en uno de los paneles de la Cumbre Anual 2022, Urgencia feroz del ahora, del sue\u00f1o a la acci\u00f3n, [&hellip;]","og_url":"https:\/\/www.fcpr.org\/en\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/","og_site_name":"Fundaci\u00f3n Comunitaria de Puerto Rico","article_publisher":"https:\/\/www.facebook.com\/FundacionComunitaria","article_published_time":"2022-08-05T13:48:23+00:00","article_modified_time":"2023-03-21T15:40:05+00:00","og_image":[{"width":1055,"height":585,"url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png","type":"image\/png"}],"author":"Libni Sanjurjo","twitter_card":"summary_large_image","twitter_creator":"@FComunitaria","twitter_site":"@FComunitaria","twitter_misc":{"Written by":"Libni Sanjurjo","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#article","isPartOf":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/"},"author":{"name":"Libni Sanjurjo","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/49ddf8247898f4a287fad4df52650612"},"headline":"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra","datePublished":"2022-08-05T13:48:23+00:00","dateModified":"2023-03-21T15:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/"},"wordCount":744,"commentCount":0,"publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"image":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png","keywords":["Comunicado","Equidad Racial"],"articleSection":["comunicados"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/","url":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/","name":"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra - Fundaci\u00f3n Comunitaria de Puerto Rico","isPartOf":{"@id":"https:\/\/www.fcpr.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#primaryimage"},"image":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png","datePublished":"2022-08-05T13:48:23+00:00","dateModified":"2023-03-21T15:40:05+00:00","breadcrumb":{"@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#primaryimage","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2022\/08\/2022-BPM-Summit-Poster-min-e1659707280567.png","width":1055,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcpr.org\/celebraran-dialogo-sobre-descolonizacion-de-la-filantropia-en-el-caribe-durante-conferencia-anual-internacional-del-mes-de-la-filantropia-negra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fcpr.org\/"},{"@type":"ListItem","position":2,"name":"Celebrar\u00e1n di\u00e1logo sobre descolonizaci\u00f3n de la filantrop\u00eda en el Caribe durante conferencia anual internacional del Mes de la Filantrop\u00eda Negra"}]},{"@type":"WebSite","@id":"https:\/\/www.fcpr.org\/#website","url":"https:\/\/www.fcpr.org\/","name":"Puerto Rico Community Foundation","description":"Strengthening Community Capital","publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcpr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fcpr.org\/#organization","name":"Puerto Rico Community Foundation","url":"https:\/\/www.fcpr.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","width":221,"height":32,"caption":"Fundaci\u00f3n Comunitaria de Puerto Rico"},"image":{"@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionComunitaria","https:\/\/x.com\/FComunitaria","https:\/\/www.instagram.com\/fundacioncomunitaria\/","https:\/\/www.youtube.com\/channel\/UCGGW21eIGw6NRin0BrylmWg"]},{"@type":"Person","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/49ddf8247898f4a287fad4df52650612","name":"Libni Sanjurjo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","caption":"Libni Sanjurjo"},"sameAs":["https:\/\/fcpr.org"],"url":"https:\/\/www.fcpr.org\/en\/author\/lisanfcpr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/11582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/comments?post=11582"}],"version-history":[{"count":1,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/11582\/revisions"}],"predecessor-version":[{"id":11583,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/11582\/revisions\/11583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media\/11584"}],"wp:attachment":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media?parent=11582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/categories?post=11582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/tags?post=11582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}