{"id":9678,"date":"2021-03-24T20:25:31","date_gmt":"2021-03-24T20:25:31","guid":{"rendered":"https:\/\/fcpr.org\/?p=9678"},"modified":"2021-03-24T21:00:42","modified_gmt":"2021-03-24T21:00:42","slug":"educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias","status":"publish","type":"post","link":"https:\/\/www.fcpr.org\/en\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/","title":{"rendered":"Educators and social workers strengthen skills to improve interaction with families"},"content":{"rendered":"<p>Dos educadores y tres trabajadores sociales fortalecieron destrezas y habilidades que les permitir\u00e1n mejorar su interacci\u00f3n con las familias que sirven en el entorno escolar.<\/p>\n\n\n\n<p>El grupo estudi\u00f3 sobre pr\u00e1cticas probadas y efectivas para promover relaciones familiares saludables, enfocadas en el desarrollo infantil y el impacto que tienen las relaciones entre padres y madres en las vidas de sus hijos e hijas. Como parte del proceso de aprendizaje, las personas participantes tomaron conciencia sobre sus propios comportamientos, sentimientos y motivadores, y c\u00f3mo estos pueden influir en su interacci\u00f3n con las familias.<\/p>\n\n\n\n<p>La certificaci\u00f3n profesional a la que tuvieron acceso fue ofrecida por la organizaci\u00f3n <em>Fathers and Families Coalition of America<\/em> (FFCA), gracias a una inversi\u00f3n filantr\u00f3pica de la <strong>Puerto Rico Community Foundation <\/strong>(FCPR).<\/p>\n\n\n\n<p>FFCA es una entidad sin fines de lucro y originada en California para responder a las necesidades de adiestramiento y servicios dirigidos a profesionales que atienden las necesidades y situaciones de&nbsp; familias y menores de edad en situaci\u00f3n de pobreza. La organizaci\u00f3n est\u00e1 acreditada por la <em>National Association of Social Workers<\/em> (NASW), Cap\u00edtulo de Arizona, y en Puerto Rico, est\u00e1 activa a trav\u00e9s del <em>Leadership and Management Institute<\/em>, organizaci\u00f3n fundada recientemente por Aida D\u00edaz.&nbsp;<\/p>\n\n\n\n<p>El adiestramiento de la FFCA se llev\u00f3 a cabo el pasado 23 y 24 de febrero en la Universidad Interamericana de Puerto Rico, Recinto Ponce.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-768x1024.jpg\" alt=\"\" class=\"wp-image-9680\" width=\"384\" height=\"512\" srcset=\"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-768x1024.jpg 768w, https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-225x300.jpg 225w, https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-1152x1536.jpg 1152w, https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-1536x2048.jpg 1536w, https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-3-scaled.jpg 1920w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><figcaption>Manual de trabajo entregado a los participantes. <\/figcaption><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Dos educadores y tres trabajadores sociales fortalecieron destrezas y habilidades que les permitir\u00e1n mejorar su interacci\u00f3n con las familias que sirven en el entorno escolar. El grupo estudi\u00f3 sobre pr\u00e1cticas probadas y efectivas para promover relaciones familiares saludables, enfocadas en el desarrollo infantil y el impacto que tienen las relaciones entre padres y madres en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[36],"tags":[122,183],"class_list":["post-9678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-educacion","tag-maestros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias - Fundaci\u00f3n Comunitaria de Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcpr.org\/en\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias\" \/>\n<meta property=\"og:description\" content=\"Dos educadores y tres trabajadores sociales fortalecieron destrezas y habilidades que les permitir\u00e1n mejorar su interacci\u00f3n con las familias que sirven en el entorno escolar. El grupo estudi\u00f3 sobre pr\u00e1cticas probadas y efectivas para promover relaciones familiares saludables, enfocadas en el desarrollo infantil y el impacto que tienen las relaciones entre padres y madres en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcpr.org\/en\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Comunitaria de Puerto Rico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionComunitaria\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T20:25:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-24T21:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Libni Sanjurjo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:site\" content=\"@FComunitaria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Libni Sanjurjo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/\"},\"author\":{\"name\":\"Libni Sanjurjo\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/49ddf8247898f4a287fad4df52650612\"},\"headline\":\"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias\",\"datePublished\":\"2021-03-24T20:25:31+00:00\",\"dateModified\":\"2021-03-24T21:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lapiz-1.jpg\",\"keywords\":[\"Educaci\u00f3n\",\"Maestros\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/\",\"name\":\"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias - Fundaci\u00f3n Comunitaria de Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lapiz-1.jpg\",\"datePublished\":\"2021-03-24T20:25:31+00:00\",\"dateModified\":\"2021-03-24T21:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lapiz-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lapiz-1.jpg\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fcpr.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#website\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"description\":\"Fortaleciendo el Capital Comunitario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fcpr.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#organization\",\"name\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"contentUrl\":\"https:\\\/\\\/www.fcpr.org\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo-corp-red.png\",\"width\":221,\"height\":32,\"caption\":\"Fundaci\u00f3n Comunitaria de Puerto Rico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionComunitaria\",\"https:\\\/\\\/x.com\\\/FComunitaria\",\"https:\\\/\\\/www.instagram.com\\\/fundacioncomunitaria\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGGW21eIGw6NRin0BrylmWg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fcpr.org\\\/#\\\/schema\\\/person\\\/49ddf8247898f4a287fad4df52650612\",\"name\":\"Libni Sanjurjo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g\",\"caption\":\"Libni Sanjurjo\"},\"sameAs\":[\"https:\\\/\\\/fcpr.org\"],\"url\":\"https:\\\/\\\/www.fcpr.org\\\/en\\\/author\\\/lisanfcpr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias - Fundaci\u00f3n Comunitaria de Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcpr.org\/en\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/","og_locale":"en_US","og_type":"article","og_title":"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias","og_description":"Dos educadores y tres trabajadores sociales fortalecieron destrezas y habilidades que les permitir\u00e1n mejorar su interacci\u00f3n con las familias que sirven en el entorno escolar. El grupo estudi\u00f3 sobre pr\u00e1cticas probadas y efectivas para promover relaciones familiares saludables, enfocadas en el desarrollo infantil y el impacto que tienen las relaciones entre padres y madres en [&hellip;]","og_url":"https:\/\/www.fcpr.org\/en\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/","og_site_name":"Fundaci\u00f3n Comunitaria de Puerto Rico","article_publisher":"https:\/\/www.facebook.com\/FundacionComunitaria","article_published_time":"2021-03-24T20:25:31+00:00","article_modified_time":"2021-03-24T21:00:42+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg","type":"image\/jpeg"}],"author":"Libni Sanjurjo","twitter_card":"summary_large_image","twitter_creator":"@FComunitaria","twitter_site":"@FComunitaria","twitter_misc":{"Written by":"Libni Sanjurjo","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#article","isPartOf":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/"},"author":{"name":"Libni Sanjurjo","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/49ddf8247898f4a287fad4df52650612"},"headline":"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias","datePublished":"2021-03-24T20:25:31+00:00","dateModified":"2021-03-24T21:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"image":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg","keywords":["Educaci\u00f3n","Maestros"],"articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/","url":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/","name":"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias - Fundaci\u00f3n Comunitaria de Puerto Rico","isPartOf":{"@id":"https:\/\/www.fcpr.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#primaryimage"},"image":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg","datePublished":"2021-03-24T20:25:31+00:00","dateModified":"2021-03-24T21:00:42+00:00","breadcrumb":{"@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#primaryimage","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2021\/03\/lapiz-1.jpg","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcpr.org\/educadores-y-trabajadores-sociales-fortalecen-habilidades-para-mejorar-interaccion-con-familias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fcpr.org\/"},{"@type":"ListItem","position":2,"name":"Educadores y trabajadores sociales fortalecen habilidades para mejorar interacci\u00f3n con familias"}]},{"@type":"WebSite","@id":"https:\/\/www.fcpr.org\/#website","url":"https:\/\/www.fcpr.org\/","name":"Puerto Rico Community Foundation","description":"Strengthening Community Capital","publisher":{"@id":"https:\/\/www.fcpr.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcpr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fcpr.org\/#organization","name":"Puerto Rico Community Foundation","url":"https:\/\/www.fcpr.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","contentUrl":"https:\/\/www.fcpr.org\/wp-content\/uploads\/2016\/08\/logo-corp-red.png","width":221,"height":32,"caption":"Fundaci\u00f3n Comunitaria de Puerto Rico"},"image":{"@id":"https:\/\/www.fcpr.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionComunitaria","https:\/\/x.com\/FComunitaria","https:\/\/www.instagram.com\/fundacioncomunitaria\/","https:\/\/www.youtube.com\/channel\/UCGGW21eIGw6NRin0BrylmWg"]},{"@type":"Person","@id":"https:\/\/www.fcpr.org\/#\/schema\/person\/49ddf8247898f4a287fad4df52650612","name":"Libni Sanjurjo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4adea318df4c70b94a623d3f26fa06bc9ebbf768514d2cb1cb40c4ebf4c2c32?s=96&d=blank&r=g","caption":"Libni Sanjurjo"},"sameAs":["https:\/\/fcpr.org"],"url":"https:\/\/www.fcpr.org\/en\/author\/lisanfcpr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/9678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/comments?post=9678"}],"version-history":[{"count":1,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/9678\/revisions"}],"predecessor-version":[{"id":9681,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/posts\/9678\/revisions\/9681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media\/9679"}],"wp:attachment":[{"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/media?parent=9678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/categories?post=9678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcpr.org\/en\/wp-json\/wp\/v2\/tags?post=9678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}